{"id":10825,"date":"2023-06-28T16:26:20","date_gmt":"2023-06-28T16:26:20","guid":{"rendered":"https:\/\/sprint-3.vadrouille.wokine.dev\/produit\/seymour-2\/"},"modified":"2024-11-06T09:49:57","modified_gmt":"2024-11-06T09:49:57","slug":"modele-seymour-john-lobb-2","status":"publish","type":"product","link":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/product\/modele-seymour-john-lobb-2\/","title":{"rendered":"Seymour"},"content":{"rendered":"<p>Avec la d\u00e9marche Vadrouille, vous mettez en mouvement cette paire de chaussures John Lobb.<\/p>\n<p>Ces chaussures d&#8217;occasion, entretenues avec soin par l&#8217;\u00e9quipe Vadrouille, vivront avec vous le temps d&#8217;une autre vie.<\/p>\n<p>En achetant cette paire de Derby de chez John Lobb en seconde main, vous faites une belle action.<\/p>\n","protected":false},"excerpt":{"rendered":"<h2>Derbies John Lobb : L&#8217;alliance parfaite du style et de la qualit\u00e9<\/h2>\n<p>Vadrouille vous pr\u00e9sente cette magnifique paire de  Derby John Lobb, dans la taille 7. Confectionn\u00e9s avec soin \u00e0 partir de Velours, ces souliers de couleur Marron se combineront parfaitement avec vos tenues les plus distingu\u00e9es. En optant pour les chaussures John Lobb, marque britannique iconique, vous vous assurez une \u00e9l\u00e9gance \u00e0 la mani\u00e8re anglaise tout au long de votre quotidien.<\/p>\n<p><\/p>\n<h2>John Lobb : le nom qui s&#8217;impose pour des chaussures en cuir haut de gamme<\/h2>\n<p>Gr\u00e2ce \u00e0 son savoir-faire remarquable et \u00e0 sa ma\u00eetrise technique exceptionnelle, la marque a toujours maintenu des liens \u00e9troits avec la famille royale. D\u00e8s son retour \u00e0 Londres en 1863, John Lobb est officiellement nomm\u00e9 bottier attitr\u00e9 du prince de Galles. Il se dit m\u00eame que le prince Charles poss\u00e8de une paire de chaussures vieille de plus de 50 ans, provenant du c\u00e9l\u00e8bre atelier de mesure de St. James, situ\u00e9 dans la ville de Londres.<\/p>\n<p><\/p>\n<h3>Un service client soucieux de votre exp\u00e9rience<\/h3>\n<p>En cas de questionnement, n&#8217;h\u00e9sitez pas \u00e0 contacter le service client au 0749228911. Les sp\u00e9cialistes de Vadrouille seront disponibles pour vous fournir leurs conseils les plus pr\u00e9cieux afin de maintenir la qualit\u00e9 de vos chaussures.<\/p>\n<p> Sp\u00e9cifications techniques ref A977 &#8211;> Pour plus d\u2019informations et d\u00e9tails<br \/>\ncontactez nous : 07 49 22 89 11<\/p>\n","protected":false},"featured_media":10131,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[17,54],"product_tag":[],"class_list":{"0":"post-10825","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chaussures","7":"product_cat-johnlobb","9":"first","10":"instock","11":"sale","12":"sold-individually","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>John Lobb Seymour - Vadrouille<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"John Lobb Seymour - Vadrouille\" \/>\n<meta property=\"og:description\" content=\"Derbies John Lobb : L&#039;alliance parfaite du style et de la qualit\u00e9Vadrouille vous pr\u00e9sente cette magnifique paire de Derby John Lobb, dans la taille 7. Confectionn\u00e9s avec soin \u00e0 partir de Velours, ces souliers de couleur Marron se combineront parfaitement avec vos tenues les plus distingu\u00e9es. En optant pour les chaussures John Lobb, marque britannique iconique, vous vous assurez une \u00e9l\u00e9gance \u00e0 la mani\u00e8re anglaise tout au long de votre quotidien.John Lobb : le nom qui s&#039;impose pour des chaussures en cuir haut de gammeGr\u00e2ce \u00e0 son savoir-faire remarquable et \u00e0 sa ma\u00eetrise technique exceptionnelle, la marque a toujours maintenu des liens \u00e9troits avec la famille royale. D\u00e8s son retour \u00e0 Londres en 1863, John Lobb est officiellement nomm\u00e9 bottier attitr\u00e9 du prince de Galles. Il se dit m\u00eame que le prince Charles poss\u00e8de une paire de chaussures vieille de plus de 50 ans, provenant du c\u00e9l\u00e8bre atelier de mesure de St. James, situ\u00e9 dans la ville de Londres.Un service client soucieux de votre exp\u00e9rienceEn cas de questionnement, n&#039;h\u00e9sitez pas \u00e0 contacter le service client au 0749228911. Les sp\u00e9cialistes de Vadrouille seront disponibles pour vous fournir leurs conseils les plus pr\u00e9cieux afin de maintenir la qualit\u00e9 de vos chaussures. Sp\u00e9cifications techniques ref A977 --&gt; Pour plus d\u2019informations et d\u00e9tails contactez nous : 07 49 22 89 11\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Vadrouille\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-06T09:49:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sprint-2.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/06\/A977-1.JPG-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/\",\"url\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/\",\"name\":\"John Lobb Seymour - Vadrouille\",\"isPartOf\":{\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/06\/A977-1.JPG-scaled.webp\",\"datePublished\":\"2023-06-28T16:26:20+00:00\",\"dateModified\":\"2024-11-06T09:49:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/#primaryimage\",\"url\":\"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/06\/A977-1.JPG-scaled.webp\",\"contentUrl\":\"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/06\/A977-1.JPG-scaled.webp\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Seymour\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/#website\",\"url\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/\",\"name\":\"Vadrouille\",\"description\":\"Achetez vos chaussures haut de gamme reconditionn\u00e9es\",\"publisher\":{\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/#organization\",\"name\":\"Vadrouille\",\"url\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/02\/LOGO_VADROUILLE_Q.png\",\"contentUrl\":\"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/02\/LOGO_VADROUILLE_Q.png\",\"width\":1613,\"height\":617,\"caption\":\"Vadrouille\"},\"image\":{\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"John Lobb Seymour - Vadrouille","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/","og_locale":"en_US","og_type":"article","og_title":"John Lobb Seymour - Vadrouille","og_description":"Derbies John Lobb : L'alliance parfaite du style et de la qualit\u00e9Vadrouille vous pr\u00e9sente cette magnifique paire de Derby John Lobb, dans la taille 7. Confectionn\u00e9s avec soin \u00e0 partir de Velours, ces souliers de couleur Marron se combineront parfaitement avec vos tenues les plus distingu\u00e9es. En optant pour les chaussures John Lobb, marque britannique iconique, vous vous assurez une \u00e9l\u00e9gance \u00e0 la mani\u00e8re anglaise tout au long de votre quotidien.John Lobb : le nom qui s'impose pour des chaussures en cuir haut de gammeGr\u00e2ce \u00e0 son savoir-faire remarquable et \u00e0 sa ma\u00eetrise technique exceptionnelle, la marque a toujours maintenu des liens \u00e9troits avec la famille royale. D\u00e8s son retour \u00e0 Londres en 1863, John Lobb est officiellement nomm\u00e9 bottier attitr\u00e9 du prince de Galles. Il se dit m\u00eame que le prince Charles poss\u00e8de une paire de chaussures vieille de plus de 50 ans, provenant du c\u00e9l\u00e8bre atelier de mesure de St. James, situ\u00e9 dans la ville de Londres.Un service client soucieux de votre exp\u00e9rienceEn cas de questionnement, n'h\u00e9sitez pas \u00e0 contacter le service client au 0749228911. Les sp\u00e9cialistes de Vadrouille seront disponibles pour vous fournir leurs conseils les plus pr\u00e9cieux afin de maintenir la qualit\u00e9 de vos chaussures. Sp\u00e9cifications techniques ref A977 --> Pour plus d\u2019informations et d\u00e9tails contactez nous : 07 49 22 89 11","og_url":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/","og_site_name":"Vadrouille","article_modified_time":"2024-11-06T09:49:57+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/sprint-2.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/06\/A977-1.JPG-scaled.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/","url":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/","name":"John Lobb Seymour - Vadrouille","isPartOf":{"@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/#primaryimage"},"image":{"@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/#primaryimage"},"thumbnailUrl":"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/06\/A977-1.JPG-scaled.webp","datePublished":"2023-06-28T16:26:20+00:00","dateModified":"2024-11-06T09:49:57+00:00","breadcrumb":{"@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/#primaryimage","url":"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/06\/A977-1.JPG-scaled.webp","contentUrl":"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/06\/A977-1.JPG-scaled.webp","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/modele-seymour-john-lobb-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sprint-2.vadrouille.wokine.dev\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/sprint-2.vadrouille.wokine.dev\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Seymour"}]},{"@type":"WebSite","@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/#website","url":"https:\/\/sprint-2.vadrouille.wokine.dev\/","name":"Vadrouille","description":"Achetez vos chaussures haut de gamme reconditionn\u00e9es","publisher":{"@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sprint-2.vadrouille.wokine.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/#organization","name":"Vadrouille","url":"https:\/\/sprint-2.vadrouille.wokine.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/#\/schema\/logo\/image\/","url":"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/02\/LOGO_VADROUILLE_Q.png","contentUrl":"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/02\/LOGO_VADROUILLE_Q.png","width":1613,"height":617,"caption":"Vadrouille"},"image":{"@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/product\/10825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/comments?post=10825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/media\/10131"}],"wp:attachment":[{"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/media?parent=10825"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/product_brand?post=10825"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/product_cat?post=10825"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/product_tag?post=10825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}