{"id":44171,"date":"2025-01-31T18:46:45","date_gmt":"2025-01-31T18:46:45","guid":{"rendered":"https:\/\/sprint-3.vadrouille.wokine.dev\/produit\/olivine-3\/"},"modified":"2025-05-13T16:10:22","modified_gmt":"2025-05-13T16:10:22","slug":"olivine-3","status":"publish","type":"product","link":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/product\/olivine-3\/","title":{"rendered":"Olivine"},"content":{"rendered":"<p>Avec la d\u00e9marche Vadrouille, vous mettez en mouvement cette paire de chaussures Heschung.<\/p>\n<p>Ces chaussures d&#8217;occasion, entretenues avec soin par l&#8217;\u00e9quipe Vadrouille, vivront avec vous le temps d&#8217;une autre vie.<\/p>\n<p>En achetant cette paire de derbies de chez Heschung en seconde main, vous faites une belle action.<\/p>\n","protected":false},"excerpt":{"rendered":"<h2><strong>Votre Olivine \u00e0 la vente<\/strong><\/h2>\n<p>\nLa chaussure, si elle est bien choisie, traverse le temps. C\u2019est pourquoi chez vadrouille nous pouvons vous trouver les meilleures p\u00e9pites vintage, elles ne tra\u00eenent jamais tr\u00e8s loin, il suffit de les sortir des placards. Alors depuis notre espace de vente de chaussures d\u2019occasion vous pourrez retrouver de nombreux mod\u00e8les uniques Olivine.\n<\/p>\n<h2><strong>D\u00e9couvrez tout l\u2019univers de la chaussure d\u2019occasion<\/strong><\/h2>\n<p>\nParaboot, John Lobb, Berluti, JM Weston ou encore Church\u2019s, sont des collections que nous avons en stock, vous y trouverez s\u00fbrement votre bonheur. \u00c0 travers notre s\u00e9lection de souliers, voyagez \u00e0 travers le temps, et profitez des chaussures haut de gamme les plus rares.\n<\/p>\n<h3><strong>Besoin d&#8217;un peu d&#8217;assistance ?<\/strong><\/h3>\n<\/p>\n<p>Trouvez tous nos conseils pour l&#8217;entretien de vos chaussures<\/p>\n<p>Aidez vous de notre guide des tailles pour choisir la bonne pointure \u00e0 acheter.<\/p>\n<p>Nous sommes disponibles par message et par mail pour r\u00e9pondre \u00e0 vos questions.<\/p>\n<p>Mail : jevadrouille.com@gmail.com<\/p>\n<p>T\u00e9l\u00e9phone : 07 49 22 89 11<\/p>\n<p> Sp\u00e9cifications techniques ref A1851 &#8211;> Pour plus d\u2019informations et d\u00e9tails<br \/>\ncontactez nous : 07 49 22 89 11<\/p>\n","protected":false},"featured_media":44237,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[17,51],"product_tag":[],"class_list":{"0":"post-44171","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chaussures","7":"product_cat-heschung","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Heschung Olivine - Vadrouille<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Heschung Olivine - Vadrouille\" \/>\n<meta property=\"og:description\" content=\"Votre Olivine \u00e0 la vente    La chaussure, si elle est bien choisie, traverse le temps. C\u2019est pourquoi chez vadrouille nous pouvons vous trouver les meilleures p\u00e9pites vintage, elles ne tra\u00eenent jamais tr\u00e8s loin, il suffit de les sortir des placards. Alors depuis notre espace de vente de chaussures d\u2019occasion vous pourrez retrouver de nombreux mod\u00e8les uniques Olivine.   D\u00e9couvrez tout l\u2019univers de la chaussure d\u2019occasion    Paraboot, John Lobb, Berluti, JM Weston ou encore Church\u2019s, sont des collections que nous avons en stock, vous y trouverez s\u00fbrement votre bonheur. \u00c0 travers notre s\u00e9lection de souliers, voyagez \u00e0 travers le temps, et profitez des chaussures haut de gamme les plus rares.  Besoin d&#039;un peu d&#039;assistance ?   Trouvez tous nos conseils pour l&#039;entretien de vos chaussures  Aidez vous de notre guide des tailles pour choisir la bonne pointure \u00e0 acheter.  Nous sommes disponibles par message et par mail pour r\u00e9pondre \u00e0 vos questions.  Mail : jevadrouille.com@gmail.com  T\u00e9l\u00e9phone : 07 49 22 89 11 Sp\u00e9cifications techniques ref A1851 --&gt; Pour plus d\u2019informations et d\u00e9tails contactez nous : 07 49 22 89 11\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Vadrouille\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-13T16:10:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sprint-2.vadrouille.wokine.dev\/wp-content\/uploads\/2025\/01\/A1851-1.JPG-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/\",\"url\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/\",\"name\":\"Heschung Olivine - Vadrouille\",\"isPartOf\":{\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2025\/01\/A1851-1.JPG-scaled.webp\",\"datePublished\":\"2025-01-31T18:46:45+00:00\",\"dateModified\":\"2025-05-13T16:10:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/#primaryimage\",\"url\":\"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2025\/01\/A1851-1.JPG-scaled.webp\",\"contentUrl\":\"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2025\/01\/A1851-1.JPG-scaled.webp\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Olivine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/#website\",\"url\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/\",\"name\":\"Vadrouille\",\"description\":\"Achetez vos chaussures haut de gamme reconditionn\u00e9es\",\"publisher\":{\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/#organization\",\"name\":\"Vadrouille\",\"url\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/02\/LOGO_VADROUILLE_Q.png\",\"contentUrl\":\"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/02\/LOGO_VADROUILLE_Q.png\",\"width\":1613,\"height\":617,\"caption\":\"Vadrouille\"},\"image\":{\"@id\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Heschung Olivine - Vadrouille","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/","og_locale":"en_US","og_type":"article","og_title":"Heschung Olivine - Vadrouille","og_description":"Votre Olivine \u00e0 la vente    La chaussure, si elle est bien choisie, traverse le temps. C\u2019est pourquoi chez vadrouille nous pouvons vous trouver les meilleures p\u00e9pites vintage, elles ne tra\u00eenent jamais tr\u00e8s loin, il suffit de les sortir des placards. Alors depuis notre espace de vente de chaussures d\u2019occasion vous pourrez retrouver de nombreux mod\u00e8les uniques Olivine.   D\u00e9couvrez tout l\u2019univers de la chaussure d\u2019occasion    Paraboot, John Lobb, Berluti, JM Weston ou encore Church\u2019s, sont des collections que nous avons en stock, vous y trouverez s\u00fbrement votre bonheur. \u00c0 travers notre s\u00e9lection de souliers, voyagez \u00e0 travers le temps, et profitez des chaussures haut de gamme les plus rares.  Besoin d'un peu d'assistance ?   Trouvez tous nos conseils pour l'entretien de vos chaussures  Aidez vous de notre guide des tailles pour choisir la bonne pointure \u00e0 acheter.  Nous sommes disponibles par message et par mail pour r\u00e9pondre \u00e0 vos questions.  Mail : jevadrouille.com@gmail.com  T\u00e9l\u00e9phone : 07 49 22 89 11 Sp\u00e9cifications techniques ref A1851 --> Pour plus d\u2019informations et d\u00e9tails contactez nous : 07 49 22 89 11","og_url":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/","og_site_name":"Vadrouille","article_modified_time":"2025-05-13T16:10:22+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/sprint-2.vadrouille.wokine.dev\/wp-content\/uploads\/2025\/01\/A1851-1.JPG-scaled.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/","url":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/","name":"Heschung Olivine - Vadrouille","isPartOf":{"@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/#primaryimage"},"image":{"@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/#primaryimage"},"thumbnailUrl":"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2025\/01\/A1851-1.JPG-scaled.webp","datePublished":"2025-01-31T18:46:45+00:00","dateModified":"2025-05-13T16:10:22+00:00","breadcrumb":{"@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/#primaryimage","url":"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2025\/01\/A1851-1.JPG-scaled.webp","contentUrl":"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2025\/01\/A1851-1.JPG-scaled.webp","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/olivine-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sprint-2.vadrouille.wokine.dev\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/sprint-2.vadrouille.wokine.dev\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Olivine"}]},{"@type":"WebSite","@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/#website","url":"https:\/\/sprint-2.vadrouille.wokine.dev\/","name":"Vadrouille","description":"Achetez vos chaussures haut de gamme reconditionn\u00e9es","publisher":{"@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sprint-2.vadrouille.wokine.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/#organization","name":"Vadrouille","url":"https:\/\/sprint-2.vadrouille.wokine.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/#\/schema\/logo\/image\/","url":"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/02\/LOGO_VADROUILLE_Q.png","contentUrl":"https:\/\/sprint-3.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/02\/LOGO_VADROUILLE_Q.png","width":1613,"height":617,"caption":"Vadrouille"},"image":{"@id":"https:\/\/sprint-2.vadrouille.wokine.dev\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/product\/44171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/comments?post=44171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/media\/44237"}],"wp:attachment":[{"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/media?parent=44171"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/product_brand?post=44171"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/product_cat?post=44171"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sprint-3.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/product_tag?post=44171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}